{"id":1128,"date":"2025-09-22T11:03:53","date_gmt":"2025-09-22T09:03:53","guid":{"rendered":"https:\/\/ellecubica.it\/en\/?post_type=news&#038;p=1128"},"modified":"2026-04-08T10:26:21","modified_gmt":"2026-04-08T08:26:21","slug":"cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance","status":"publish","type":"news","link":"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/","title":{"rendered":"Cos\u2019\u00e8 il Self Talk o Dialogo Interiore: come sfruttare il dialogo interiore per aumentare le performance"},"content":{"rendered":"\n<section class=\"hero-text aligncenter plr-10 pt-200\" data-block=\"block_bf895bffdfa9e62911c14bbe2caa5174\">\n\n\n\t<div class=\"col-wrap content-wrap\">\n\t\t<div class=\"title\" data-scrollreveal=\"fade-up\">\n\n\t\t\t<div class=\"custom-breadcrumb\" data-scrollreveal=\"fade-right\"><\/div>\n\n\t\t\t\t\t\t\t<h1><\/h1>\n\t\t\t\n\t\t<\/div>\n\n\n\t\t\n\n\t<\/div>\n\n\t\n\n<\/section>\n\n\n\n\n\n\n<div class=\"space aligncenter\" data-block=\"block_7a9660c17ff20c63067fa8d1a91ed4f7\" style=\"height:30px;background-color:#ffffff;\"><\/div>\n\n\n\n\n<section class=\"immagine aligncenter plr-10 azzurro\" data-block=\"block_29755b9a06d7e687ced1abd9eee66bd6\" data-scrollreveal=\"fade-up\">\n\n\n\t<div class=\"wrapper\">\n\t\t<img decoding=\"async\" src=\"https:\/\/ellecubica.it\/wp-content\/uploads\/sites\/3\/ELLECUBICA_Calendario-inserzioni-16.jpg\" class=\"cover\" alt=\"\">\n\n\t\t<svg width=\"305\" height=\"309\" viewBox=\"0 0 305 309\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M105.611 0H0V309H304.442V200.421H105.611V0Z\" fill=\"#164f78\"\/>\n<\/svg>\n\n\n\t<\/div>\n\n<\/section>\n\n\n\n\n\n\n<div class=\"space aligncenter\" data-block=\"block_01d623b9f3709caf572a0bb9db2fa82d\" style=\"height:50px;background-color:#ffffff;\"><\/div>\n\n\n\n\n<section class=\"paragrafo aligncenter plr-10\" data-block=\"block_404e59e33cee6fbfb4908588850cfbca\" data-scrollreveal=\"fade-up\">\n\n\t\t\t<div class=\"text\">\n\t\t\t\t\t\t\t<p><b>In media, rivolgiamo a noi stessi circa 51.000 parole al giorno.<\/b>\u00a0Questo dato ti stupisce? \u00c8 chiaro che essere consci del proprio dialogo interiore non \u00e8 cosa scontata. Tuttavia, il self talk pu\u00f2 influire sui risultati che otteniamo sia in positivo che in negativo.<\/p>\n<p>Per questo motivo, \u00e8 importante essere consapevoli del proprio dialogo interiore in modo tale da ottenere un miglioramento delle nostre performance sia in ambito life che business.<\/p>\n<h2><b>Cos\u2019\u00e8 il self talk?<\/b><\/h2>\n<p><b>Il self talk si compone di due elementi: pensieri e parole. Pensieri e parole creano un dialogo interiore funzionale nel momento in cui sono coerenti e, di conseguenza, motivano alla performance.<\/b>\u00a0D\u2019altra parte, il self talk \u00e8 disfunzionale quando \u00e8 ostativo e demotivante per la performance.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1741\" src=\"https:\/\/ellecubica.it\/en\/wp-content\/uploads\/sites\/3\/Screenshot-2025-09-15-alle-10.08.08.png\" alt=\"\" width=\"534\" height=\"350\" \/><\/p>\n<p><b><span data-contrast=\"none\">Il modo in cui parliamo a noi stessi influisce sulle nostre azioni e i nostri comportamenti. A volte, utilizziamo con noi stessi delle parole che non useremmo mai con nessun\u2019altro, magari, risultando, nei nostri confronti, fin troppo severi.\u00a0<\/span><\/b><span data-contrast=\"auto\">Anche i pensieri automatici negativi (PAN) fanno parte del nostro dialogo interiore. In psicologia, si dice che questi siano dei pensieri \u201ctelegrafici\u201d: entrano in testa senza essere sottoposti a critica e li consideriamo la verit\u00e0 pi\u00f9 assoluta. Ti risuona?<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">In genere, questi pensieri rendono il nostro dialogo interiore non affine alla performance e non ci permettono di sfruttare al massimo le nostre potenzialit\u00e0.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Ognuno di noi ha le proprie convinzioni, su\u00a0se\u00a0stesso e sugli altri. Il nostro cervello, per\u00f2 non \u00e8 in grado di distinguere i pensieri dagli eventi reali e questo pu\u00f2 avere delle conseguenze negative sull\u2019attenzione, la memoria o sulla qualit\u00e0 delle nostre prestazioni, ad esempio.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h2><strong>Come rendere efficace il dialogo interiore?\u00a0<\/strong><\/h2>\n<p><span data-contrast=\"auto\">Le coaching skill ci possono aiutare a diventare pi\u00f9 consapevoli del nostro self talk e a fare in modo di dare spazio ai pensieri e alle parole che si rivelano funzionali per noi stessi.\u00a0<\/span><\/p>\n<h2><strong>Come agisce un Coach?<\/strong><\/h2>\n<p><span data-contrast=\"auto\">Analizziamo tre distorsioni cognitive e le rispettive domande che un Coach potrebbe porre:<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"auto\">\u201cSono sicuro che non convincer\u00f2 il\u00a0prospect\u201d<\/span><\/i><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Coach: \u201cCosa ti rende sicuro di questo?\u201d<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"auto\">\u201cIncredibile, non riesco mai a portare nulla a termine\u201d<\/span><\/i><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Coach: \u201cQuando \u00e8 stata l\u2019ultima volta che ti \u00e8 accaduto?\u201d<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"auto\">\u201cSono un disastro, sono tutti migliori di me\u2026\u201d<\/span><\/i><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Coach: \u201cChi sono questi \u201ctutti\u201d?\u201d<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Il Self Talk, per quanto si componga \u201csolo\u201d di parole e pensieri, pu\u00f2 influenzare le nostre azioni: infatti,\u00a0<\/span><b><span data-contrast=\"auto\">il nostro cervello non vede differenza tra eventi reali e pensieri ed \u00e8 proprio qui che entra in gioco il Coaching, come strumento per differenziare ci\u00f2 che \u00e8 reale e ci\u00f2 che si limita ad essere solo un pensiero.<\/span><\/b><span data-contrast=\"auto\">\u00a0Nel nostro Master in Coaching approfondiamo come lavorare in ottima consapevolezza e concreta gli argomenti del dialogo interiore, distorsioni cognitive e\u00a0bias\u00a0cognitivi.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n\n\t\t\t\t\t<\/div>\n\t\n<\/section>\n\n\n\n\n\n\n<section class=\"cta-news aligncenter plr-10 pt-100 pb-100\" data-scrollreveal=\"fade-up\" data-block=\"block_1bb4228d4744e539eeecd6c8e93e20ce\">\n\n\t\t\t<div class=\"text\">\n\t\t\t<h4><strong>Vuoi ricevere maggiori informazioni sul nostro Master in Coaching Dinamico? <\/strong><strong>Clicca qui per scaricare la brochure del percorso:<\/strong><\/h4>\n\n\t\t<\/div>\n\t\n\t\t\t<div class=\"cta-wrap\">\n\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/academy.ellecubica.it\/brochure-mastercoaching\" title=\"\" class=\"btn btn-dark-blue btn-\">MASTER IN COACHING DINAMICO<\/a>\n\n\t\t\t\t\t<\/div>\n\t\n<\/section>\n\n\n\n<section class=\"condividi aligncenter plr-10 pb-100\" data-block=\"block_e2b8c92de27a18e8837385dfba031f44\" data-scrollreveal=\"fade-up\">\n\n\n\t<div class=\"wrapper\">\n\t\t<h3><\/h3>\n\n\n\t\t<div class=\"social fz-22\">\n\n\t\t\t<a href=\"https:\/\/api.whatsapp.com\/send?text=Guarda questa pagina: https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/\" data-action=\"share\/whatsapp\/share\" target=\"_blank\"><\/a>\n\n\t\t\t<a href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/\" target=\"_blank\"><\/a>\n\n\t\t\t<a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/\" target=\"_blank\"><\/a>\n\n\n\t\t<\/div>\n\n\t<\/div>\n\n\n<\/section>\n\n\n\n<section class=\"anteprime-news aligncenter pb-100\" data-block=\"block_c207be5217856454498c7ff4d14d9929\" data-scrollreveal=\"fade-up\">\n\n\n\t<div class=\"wrapper\">\n\t\t\n\t\n\t<article class=\"tease tease-news\">\n\n\t\t\t\t\t<a href=\"https:\/\/ellecubica.it\/en\/coaching-blog\/collaborazione-forzata-il-costo-dei-team-disfunzionali\/\">\n\t\t\t\t<span class=\"d-none\">Collaborazione forzata: il costo dei team disfunzionali<\/span>\n\t\t\t\t<div class=\"image-wrap\">\n\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ellecubica.it\/wp-content\/uploads\/sites\/3\/calendario-post-ellecubica-2-1080-x-1350-px-12-1080x0-c-default.jpg\" alt=\"\" class=\"cover\">\n\t\t\t\t\t<svg width=\"149\" height=\"151\" viewBox=\"0 0 149 151\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M51.6878 0H0V151H149V97.9403H51.6878V0Z\" fill=\"white\"\/>\n<\/svg>\n\n\n\t\t\t\t<\/div>\n\t\t\t<\/a>\n\t\t\n\n\t\t<div class=\"text-wrap\">\n\t\t\t<div class=\"term uppercase\">\n\t\t\t\tArticles\n\t\t\t<\/div>\n\n\t\t\t<h4 class=\"title\">\n\t\t\t\tCollaborazione forzata: il costo dei team disfunzionali\n\t\t\t<\/h4>\n\n\t\t\t<div class=\"text\">\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t<a href=\"https:\/\/ellecubica.it\/en\/coaching-blog\/collaborazione-forzata-il-costo-dei-team-disfunzionali\/\">\n\t\t\t\t<div class=\"cta\">\n\t\t\t\t\t<span><\/span>\n\t\t\t\t\t<svg width=\"13\" height=\"10\" viewBox=\"0 0 13 10\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.00704 0.198869L12.1725 4.51989C12.4282 4.78505 12.4282 5.21495 12.1725 5.48011L8.00704 9.80113C7.75143 10.0663 7.33699 10.0663 7.08138 9.80113C6.82576 9.53597 6.82576 9.10606 7.08138 8.8409L10.1295 5.67898H0.364258V4.32102H10.1295L7.08138 1.1591C6.82576 0.893936 6.82576 0.464029 7.08138 0.198869C7.33699 -0.0662898 7.75143 -0.0662898 8.00704 0.198869Z\" fill=\"white\"\/>\n<\/svg>\n\n\t\t\t\t<\/div>\n\t\t\t<\/a>\n\n\n\t\t<\/div>\n\n\n\t<\/article>\n\n\n\t\n\t<article class=\"tease tease-news\">\n\n\t\t\t\t\t<a href=\"https:\/\/ellecubica.it\/en\/coaching-blog\/il-burn-out-come-conseguenza-assenza-significato\/\">\n\t\t\t\t<span class=\"d-none\">Il burn-out come conseguenza dell&#8217;assenza di significato<\/span>\n\t\t\t\t<div class=\"image-wrap\">\n\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ellecubica.it\/wp-content\/uploads\/sites\/3\/ELLECUBICA_Calendario-inserzioni-53-1-1080x0-c-default.jpg\" alt=\"\" class=\"cover\">\n\t\t\t\t\t<svg width=\"149\" height=\"151\" viewBox=\"0 0 149 151\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M51.6878 0H0V151H149V97.9403H51.6878V0Z\" fill=\"white\"\/>\n<\/svg>\n\n\n\t\t\t\t<\/div>\n\t\t\t<\/a>\n\t\t\n\n\t\t<div class=\"text-wrap\">\n\t\t\t<div class=\"term uppercase\">\n\t\t\t\tArticles\n\t\t\t<\/div>\n\n\t\t\t<h4 class=\"title\">\n\t\t\t\tIl burn-out come conseguenza dell&#8217;assenza di significato\n\t\t\t<\/h4>\n\n\t\t\t<div class=\"text\">\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t<a href=\"https:\/\/ellecubica.it\/en\/coaching-blog\/il-burn-out-come-conseguenza-assenza-significato\/\">\n\t\t\t\t<div class=\"cta\">\n\t\t\t\t\t<span><\/span>\n\t\t\t\t\t<svg width=\"13\" height=\"10\" viewBox=\"0 0 13 10\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.00704 0.198869L12.1725 4.51989C12.4282 4.78505 12.4282 5.21495 12.1725 5.48011L8.00704 9.80113C7.75143 10.0663 7.33699 10.0663 7.08138 9.80113C6.82576 9.53597 6.82576 9.10606 7.08138 8.8409L10.1295 5.67898H0.364258V4.32102H10.1295L7.08138 1.1591C6.82576 0.893936 6.82576 0.464029 7.08138 0.198869C7.33699 -0.0662898 7.75143 -0.0662898 8.00704 0.198869Z\" fill=\"white\"\/>\n<\/svg>\n\n\t\t\t\t<\/div>\n\t\t\t<\/a>\n\n\n\t\t<\/div>\n\n\n\t<\/article>\n\n\n\t\n\t<article class=\"tease tease-news\">\n\n\t\t\t\t\t<a href=\"https:\/\/ellecubica.it\/en\/coaching-blog\/quando-alzare-l-asticella-demotiva-e-come-evitarlo\/\">\n\t\t\t\t<span class=\"d-none\">Quando alzare l&#8217;asticella demotiva e come evitarlo<\/span>\n\t\t\t\t<div class=\"image-wrap\">\n\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ellecubica.it\/wp-content\/uploads\/sites\/3\/ELLECUBICA_Calendario-inserzioni-47-1-1080x0-c-default.jpg\" alt=\"\" class=\"cover\">\n\t\t\t\t\t<svg width=\"149\" height=\"151\" viewBox=\"0 0 149 151\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M51.6878 0H0V151H149V97.9403H51.6878V0Z\" fill=\"white\"\/>\n<\/svg>\n\n\n\t\t\t\t<\/div>\n\t\t\t<\/a>\n\t\t\n\n\t\t<div class=\"text-wrap\">\n\t\t\t<div class=\"term uppercase\">\n\t\t\t\tArticles\n\t\t\t<\/div>\n\n\t\t\t<h4 class=\"title\">\n\t\t\t\tQuando alzare l&#8217;asticella demotiva e come evitarlo\n\t\t\t<\/h4>\n\n\t\t\t<div class=\"text\">\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t<a href=\"https:\/\/ellecubica.it\/en\/coaching-blog\/quando-alzare-l-asticella-demotiva-e-come-evitarlo\/\">\n\t\t\t\t<div class=\"cta\">\n\t\t\t\t\t<span><\/span>\n\t\t\t\t\t<svg width=\"13\" height=\"10\" viewBox=\"0 0 13 10\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.00704 0.198869L12.1725 4.51989C12.4282 4.78505 12.4282 5.21495 12.1725 5.48011L8.00704 9.80113C7.75143 10.0663 7.33699 10.0663 7.08138 9.80113C6.82576 9.53597 6.82576 9.10606 7.08138 8.8409L10.1295 5.67898H0.364258V4.32102H10.1295L7.08138 1.1591C6.82576 0.893936 6.82576 0.464029 7.08138 0.198869C7.33699 -0.0662898 7.75143 -0.0662898 8.00704 0.198869Z\" fill=\"white\"\/>\n<\/svg>\n\n\t\t\t\t<\/div>\n\t\t\t<\/a>\n\n\n\t\t<\/div>\n\n\n\t<\/article>\n\n\n\t\n\t<article class=\"tease tease-news\">\n\n\t\t\t\t\t<a href=\"https:\/\/ellecubica.it\/en\/coaching-blog\/i-costi-segreti-di-una-riunione-inutile\/\">\n\t\t\t\t<span class=\"d-none\">I costi segreti di una riunione inutile<\/span>\n\t\t\t\t<div class=\"image-wrap\">\n\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ellecubica.it\/wp-content\/uploads\/sites\/3\/ELLECUBICA_Calendario-inserzioni-46-1-1080x0-c-default.jpg\" alt=\"\" class=\"cover\">\n\t\t\t\t\t<svg width=\"149\" height=\"151\" viewBox=\"0 0 149 151\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M51.6878 0H0V151H149V97.9403H51.6878V0Z\" fill=\"white\"\/>\n<\/svg>\n\n\n\t\t\t\t<\/div>\n\t\t\t<\/a>\n\t\t\n\n\t\t<div class=\"text-wrap\">\n\t\t\t<div class=\"term uppercase\">\n\t\t\t\tArticles\n\t\t\t<\/div>\n\n\t\t\t<h4 class=\"title\">\n\t\t\t\tI costi segreti di una riunione inutile\n\t\t\t<\/h4>\n\n\t\t\t<div class=\"text\">\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t<a href=\"https:\/\/ellecubica.it\/en\/coaching-blog\/i-costi-segreti-di-una-riunione-inutile\/\">\n\t\t\t\t<div class=\"cta\">\n\t\t\t\t\t<span><\/span>\n\t\t\t\t\t<svg width=\"13\" height=\"10\" viewBox=\"0 0 13 10\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.00704 0.198869L12.1725 4.51989C12.4282 4.78505 12.4282 5.21495 12.1725 5.48011L8.00704 9.80113C7.75143 10.0663 7.33699 10.0663 7.08138 9.80113C6.82576 9.53597 6.82576 9.10606 7.08138 8.8409L10.1295 5.67898H0.364258V4.32102H10.1295L7.08138 1.1591C6.82576 0.893936 6.82576 0.464029 7.08138 0.198869C7.33699 -0.0662898 7.75143 -0.0662898 8.00704 0.198869Z\" fill=\"white\"\/>\n<\/svg>\n\n\t\t\t\t<\/div>\n\t\t\t<\/a>\n\n\n\t\t<\/div>\n\n\n\t<\/article>\n\n\t<\/div>\n\n\t\n\n<\/section>\n\n\n\n<section class=\"posts-nav aligncenter color-white\" data-block=\"block_ad0b426e5aa39bd32a652c5a165b4d5c\" data-scrollreveal=\"fade-up\">\n\n\n\t<div class=\"arrows-wrap plr-5\" data-scrollreveal=\"fade-up\">\n\n\t\t<a href=\"\" class=\"arrow sl-prev hide\">\n\n\t\t\t<div class=\"item-link\">\n\t\t\t\t<svg width=\"13\" height=\"10\" viewBox=\"0 0 13 10\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.00704 0.198869L12.1725 4.51989C12.4282 4.78505 12.4282 5.21495 12.1725 5.48011L8.00704 9.80113C7.75143 10.0663 7.33699 10.0663 7.08138 9.80113C6.82576 9.53597 6.82576 9.10606 7.08138 8.8409L10.1295 5.67898H0.364258V4.32102H10.1295L7.08138 1.1591C6.82576 0.893936 6.82576 0.464029 7.08138 0.198869C7.33699 -0.0662898 7.75143 -0.0662898 8.00704 0.198869Z\" fill=\"white\"\/>\n<\/svg>\n\n\n\t\t\t<\/div>\n\n\t\t\t<span><\/span>\n\n\t\t<\/a>\n\n\n\t\t<a href=\"https:\/\/ellecubica.it\/en\/blog-coaching\/\" class=\"btn btn-white\">\n\t\t\t\n\t\t<\/a>\n\n\t\t<a href=\"\" class=\"arrow sl-next\">\n\n\t\t\t<span><\/span>\n\n\t\t\t<div class=\"item-link\">\n\t\t\t\t<svg width=\"13\" height=\"10\" viewBox=\"0 0 13 10\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.00704 0.198869L12.1725 4.51989C12.4282 4.78505 12.4282 5.21495 12.1725 5.48011L8.00704 9.80113C7.75143 10.0663 7.33699 10.0663 7.08138 9.80113C6.82576 9.53597 6.82576 9.10606 7.08138 8.8409L10.1295 5.67898H0.364258V4.32102H10.1295L7.08138 1.1591C6.82576 0.893936 6.82576 0.464029 7.08138 0.198869C7.33699 -0.0662898 7.75143 -0.0662898 8.00704 0.198869Z\" fill=\"white\"\/>\n<\/svg>\n\n\n\t\t\t<\/div>\n\n\t\t<\/a>\n\n\t<\/div>\n\n\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":2215,"template":"","meta":{"_acf_changed":true},"cat-news":[10],"class_list":["post-1128","news","type-news","status-publish","has-post-thumbnail","hentry","cat-news-articles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cos\u2019\u00e8 il Self Talk o Dialogo Interiore: come sfruttare il dialogo interiore per aumentare le performance | Ellecubica<\/title>\n<meta name=\"description\" content=\"Cos\u2019\u00e8 il Self Talk o Dialogo Interiore: come sfruttare il dialogo interiore per aumentare le performance. Stay updated with the latest insights from Ellecubica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cos\u2019\u00e8 il Self Talk o Dialogo Interiore: come sfruttare il dialogo interiore per aumentare le performance | Ellecubica\" \/>\n<meta property=\"og:description\" content=\"Cos\u2019\u00e8 il Self Talk o Dialogo Interiore: come sfruttare il dialogo interiore per aumentare le performance. Stay updated with the latest insights from Ellecubica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/\" \/>\n<meta property=\"og:site_name\" content=\"Ellecubica EN\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-08T08:26:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ellecubica.it\/wp-content\/uploads\/sites\/3\/ELLECUBICA_Calendario-inserzioni-16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1072\" \/>\n\t<meta property=\"og:image:height\" content=\"707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/\",\"url\":\"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/\",\"name\":\"Cos\u2019\u00e8 il Self Talk o Dialogo Interiore: come sfruttare il dialogo interiore per aumentare le performance | Ellecubica\",\"isPartOf\":{\"@id\":\"https:\/\/ellecubica.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ellecubica.it\/wp-content\/uploads\/sites\/3\/ELLECUBICA_Calendario-inserzioni-16.jpg\",\"datePublished\":\"2025-09-22T09:03:53+00:00\",\"dateModified\":\"2026-04-08T08:26:21+00:00\",\"description\":\"Cos\u2019\u00e8 il Self Talk o Dialogo Interiore: come sfruttare il dialogo interiore per aumentare le performance. Stay updated with the latest insights from Ellecubica.\",\"breadcrumb\":{\"@id\":\"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/#primaryimage\",\"url\":\"https:\/\/ellecubica.it\/wp-content\/uploads\/sites\/3\/ELLECUBICA_Calendario-inserzioni-16.jpg\",\"contentUrl\":\"https:\/\/ellecubica.it\/wp-content\/uploads\/sites\/3\/ELLECUBICA_Calendario-inserzioni-16.jpg\",\"width\":1072,\"height\":707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ellecubica.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/ellecubica.it\/en\/blog-coaching\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cos\u2019\u00e8 il Self Talk o Dialogo Interiore: come sfruttare il dialogo interiore per aumentare le performance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ellecubica.it\/en\/#website\",\"url\":\"https:\/\/ellecubica.it\/en\/\",\"name\":\"Ellecubica\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ellecubica.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cos\u2019\u00e8 il Self Talk o Dialogo Interiore: come sfruttare il dialogo interiore per aumentare le performance | Ellecubica","description":"Cos\u2019\u00e8 il Self Talk o Dialogo Interiore: come sfruttare il dialogo interiore per aumentare le performance. Stay updated with the latest insights from Ellecubica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/","og_locale":"en_US","og_type":"article","og_title":"Cos\u2019\u00e8 il Self Talk o Dialogo Interiore: come sfruttare il dialogo interiore per aumentare le performance | Ellecubica","og_description":"Cos\u2019\u00e8 il Self Talk o Dialogo Interiore: come sfruttare il dialogo interiore per aumentare le performance. Stay updated with the latest insights from Ellecubica.","og_url":"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/","og_site_name":"Ellecubica EN","article_modified_time":"2026-04-08T08:26:21+00:00","og_image":[{"width":1072,"height":707,"url":"https:\/\/ellecubica.it\/wp-content\/uploads\/sites\/3\/ELLECUBICA_Calendario-inserzioni-16.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/","url":"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/","name":"Cos\u2019\u00e8 il Self Talk o Dialogo Interiore: come sfruttare il dialogo interiore per aumentare le performance | Ellecubica","isPartOf":{"@id":"https:\/\/ellecubica.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/#primaryimage"},"image":{"@id":"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/#primaryimage"},"thumbnailUrl":"https:\/\/ellecubica.it\/wp-content\/uploads\/sites\/3\/ELLECUBICA_Calendario-inserzioni-16.jpg","datePublished":"2025-09-22T09:03:53+00:00","dateModified":"2026-04-08T08:26:21+00:00","description":"Cos\u2019\u00e8 il Self Talk o Dialogo Interiore: come sfruttare il dialogo interiore per aumentare le performance. Stay updated with the latest insights from Ellecubica.","breadcrumb":{"@id":"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/#primaryimage","url":"https:\/\/ellecubica.it\/wp-content\/uploads\/sites\/3\/ELLECUBICA_Calendario-inserzioni-16.jpg","contentUrl":"https:\/\/ellecubica.it\/wp-content\/uploads\/sites\/3\/ELLECUBICA_Calendario-inserzioni-16.jpg","width":1072,"height":707},{"@type":"BreadcrumbList","@id":"https:\/\/ellecubica.it\/en\/coaching-blog\/cose-il-self-talk-o-dialogo-interiore-come-sfruttare-il-dialogo-interiore-per-aumentare-le-performance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ellecubica.it\/en\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/ellecubica.it\/en\/blog-coaching\/"},{"@type":"ListItem","position":3,"name":"Cos\u2019\u00e8 il Self Talk o Dialogo Interiore: come sfruttare il dialogo interiore per aumentare le performance"}]},{"@type":"WebSite","@id":"https:\/\/ellecubica.it\/en\/#website","url":"https:\/\/ellecubica.it\/en\/","name":"Ellecubica","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ellecubica.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/ellecubica.it\/en\/wp-json\/wp\/v2\/news\/1128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellecubica.it\/en\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/ellecubica.it\/en\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellecubica.it\/en\/wp-json\/wp\/v2\/media\/2215"}],"wp:attachment":[{"href":"https:\/\/ellecubica.it\/en\/wp-json\/wp\/v2\/media?parent=1128"}],"wp:term":[{"taxonomy":"cat-news","embeddable":true,"href":"https:\/\/ellecubica.it\/en\/wp-json\/wp\/v2\/cat-news?post=1128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}